{"id":1855,"date":"2024-12-10T21:18:51","date_gmt":"2024-12-10T20:18:51","guid":{"rendered":"https:\/\/caseificiomolisanosanmarco.it\/?post_type=product&#038;p=1855"},"modified":"2024-12-18T10:12:27","modified_gmt":"2024-12-18T09:12:27","slug":"panettone-caramello-e-cioccolato","status":"publish","type":"product","link":"https:\/\/caseificiomolisanosanmarco.it\/en\/product\/panettone-caramello-e-cioccolato\/","title":{"rendered":"Panettone caramello e cioccolato"},"content":{"rendered":"<p>Il panettone viene ottenuto con un processo di <em>lievitazione naturale<\/em> della durata di 48 ore, dal <strong>Panificio-Biscottificio Di Lella<\/strong> di Mirabello Sannitico. Tale azienda opera nel settore della panificazione da pi\u00f9 di settant\u2019anni offrendo una vasta gamma di prodotti da forno sia dolci che salati.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>INFORMAZIONI UTILI<\/strong>: Il processo di <em>lievitazione naturale<\/em> viene ottenuto grazie all\u2019utilizzo di lievito madre che, oltre a rendere i prodotti molto digeribili, funge da antimuffa naturale. Per questo motivo non sono presenti conservanti, additivi, coloranti e grassi idrogenati ma solo prodotti naturali di altissima qualit\u00e0 come farina, uova, zucchero e burro.<\/p>","protected":false},"excerpt":{"rendered":"<p>PANETTONE ARTIGIANALE A LIEVITAZIONE NATURALE 48H<\/p>\n<p><em>Dalla ricetta della tradizione, gli ingredienti semplici e genuini e le sapienti mani degli artigiani, nasce il Panettone Di Lella<\/em><\/p>\n<p><strong>INGREDIENTI<\/strong>: farina di grano tenero \u201c00\u201d,\u00a0 tuorli d\u2019uovo, burro, zucchero, lievito madre, caramello, cioccolato, miele, sali, aromi.<\/p>\n<div id=\"gtx-trans\" style=\"position: absolute; left: 513px; top: 165.01px;\">\n<div class=\"gtx-trans-icon\"><\/div>\n<\/div>","protected":false},"featured_media":1856,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[137,116],"product_tag":[],"class_list":["post-1855","product","type-product","status-publish","has-post-thumbnail","product_cat-confezione-regalo","product_cat-dolci","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.6 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Panettone caramello e cioccolato - Caseificio Molisano San Marco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/caseificiomolisanosanmarco.it\/en\/product\/panettone-caramello-e-cioccolato\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Panettone caramello e cioccolato\" \/>\n<meta property=\"og:description\" content=\"PANETTONE ARTIGIANALE A LIEVITAZIONE NATURALE 48H  Dalla ricetta della tradizione, gli ingredienti semplici e genuini e le sapienti mani degli artigiani, nasce il Panettone Di Lella  INGREDIENTI: farina di grano tenero \u201c00\u201d,\u00a0 tuorli d\u2019uovo, burro, zucchero, lievito madre, caramello, cioccolato, miele, sali, aromi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/caseificiomolisanosanmarco.it\/en\/product\/panettone-caramello-e-cioccolato\/\" \/>\n<meta property=\"og:site_name\" content=\"Caseificio Molisano San Marco\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-18T09:12:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/caseificiomolisanosanmarco.it\/wp-content\/uploads\/2024\/12\/caramello_4-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"30,00&nbsp;&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/caseificiomolisanosanmarco.it\\\/prodotto\\\/panettone-caramello-e-cioccolato\\\/\",\"url\":\"https:\\\/\\\/caseificiomolisanosanmarco.it\\\/prodotto\\\/panettone-caramello-e-cioccolato\\\/\",\"name\":\"Panettone caramello e cioccolato - Caseificio Molisano San Marco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/caseificiomolisanosanmarco.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/caseificiomolisanosanmarco.it\\\/prodotto\\\/panettone-caramello-e-cioccolato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/caseificiomolisanosanmarco.it\\\/prodotto\\\/panettone-caramello-e-cioccolato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/caseificiomolisanosanmarco.it\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/caramello_4-scaled-1.jpg\",\"datePublished\":\"2024-12-10T20:18:51+00:00\",\"dateModified\":\"2024-12-18T09:12:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/caseificiomolisanosanmarco.it\\\/prodotto\\\/panettone-caramello-e-cioccolato\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/caseificiomolisanosanmarco.it\\\/prodotto\\\/panettone-caramello-e-cioccolato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/caseificiomolisanosanmarco.it\\\/prodotto\\\/panettone-caramello-e-cioccolato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/caseificiomolisanosanmarco.it\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/caramello_4-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/caseificiomolisanosanmarco.it\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/caramello_4-scaled-1.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/caseificiomolisanosanmarco.it\\\/prodotto\\\/panettone-caramello-e-cioccolato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/caseificiomolisanosanmarco.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/caseificiomolisanosanmarco.it\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Panettone caramello e cioccolato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/caseificiomolisanosanmarco.it\\\/#website\",\"url\":\"https:\\\/\\\/caseificiomolisanosanmarco.it\\\/\",\"name\":\"Caseificio Molisano San Marco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/caseificiomolisanosanmarco.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/caseificiomolisanosanmarco.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/caseificiomolisanosanmarco.it\\\/#organization\",\"name\":\"Caseificio Molisano San Marco\",\"url\":\"https:\\\/\\\/caseificiomolisanosanmarco.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/caseificiomolisanosanmarco.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/caseificiomolisanosanmarco.it\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/LOGO-Transparent-e1610640037833.png\",\"contentUrl\":\"https:\\\/\\\/caseificiomolisanosanmarco.it\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/LOGO-Transparent-e1610640037833.png\",\"width\":150,\"height\":150,\"caption\":\"Caseificio Molisano San Marco\"},\"image\":{\"@id\":\"https:\\\/\\\/caseificiomolisanosanmarco.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<meta property=\"product:brand\" content=\"Dolci\" \/>\n<meta property=\"product:price:amount\" content=\"30.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Panettone caramello e cioccolato - Caseificio Molisano San Marco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/caseificiomolisanosanmarco.it\/en\/product\/panettone-caramello-e-cioccolato\/","og_locale":"en_GB","og_type":"article","og_title":"Panettone caramello e cioccolato","og_description":"PANETTONE ARTIGIANALE A LIEVITAZIONE NATURALE 48H  Dalla ricetta della tradizione, gli ingredienti semplici e genuini e le sapienti mani degli artigiani, nasce il Panettone Di Lella  INGREDIENTI: farina di grano tenero \u201c00\u201d,\u00a0 tuorli d\u2019uovo, burro, zucchero, lievito madre, caramello, cioccolato, miele, sali, aromi.","og_url":"https:\/\/caseificiomolisanosanmarco.it\/en\/product\/panettone-caramello-e-cioccolato\/","og_site_name":"Caseificio Molisano San Marco","article_modified_time":"2024-12-18T09:12:27+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/caseificiomolisanosanmarco.it\/wp-content\/uploads\/2024\/12\/caramello_4-scaled-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"30,00&nbsp;&euro;","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/caseificiomolisanosanmarco.it\/prodotto\/panettone-caramello-e-cioccolato\/","url":"https:\/\/caseificiomolisanosanmarco.it\/prodotto\/panettone-caramello-e-cioccolato\/","name":"Panettone caramello e cioccolato - Caseificio Molisano San Marco","isPartOf":{"@id":"https:\/\/caseificiomolisanosanmarco.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/caseificiomolisanosanmarco.it\/prodotto\/panettone-caramello-e-cioccolato\/#primaryimage"},"image":{"@id":"https:\/\/caseificiomolisanosanmarco.it\/prodotto\/panettone-caramello-e-cioccolato\/#primaryimage"},"thumbnailUrl":"https:\/\/caseificiomolisanosanmarco.it\/wp-content\/uploads\/2024\/12\/caramello_4-scaled-1.jpg","datePublished":"2024-12-10T20:18:51+00:00","dateModified":"2024-12-18T09:12:27+00:00","breadcrumb":{"@id":"https:\/\/caseificiomolisanosanmarco.it\/prodotto\/panettone-caramello-e-cioccolato\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/caseificiomolisanosanmarco.it\/prodotto\/panettone-caramello-e-cioccolato\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/caseificiomolisanosanmarco.it\/prodotto\/panettone-caramello-e-cioccolato\/#primaryimage","url":"https:\/\/caseificiomolisanosanmarco.it\/wp-content\/uploads\/2024\/12\/caramello_4-scaled-1.jpg","contentUrl":"https:\/\/caseificiomolisanosanmarco.it\/wp-content\/uploads\/2024\/12\/caramello_4-scaled-1.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/caseificiomolisanosanmarco.it\/prodotto\/panettone-caramello-e-cioccolato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/caseificiomolisanosanmarco.it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/caseificiomolisanosanmarco.it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Panettone caramello e cioccolato"}]},{"@type":"WebSite","@id":"https:\/\/caseificiomolisanosanmarco.it\/#website","url":"https:\/\/caseificiomolisanosanmarco.it\/","name":"Caseificio Molisano San Marco","description":"","publisher":{"@id":"https:\/\/caseificiomolisanosanmarco.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/caseificiomolisanosanmarco.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/caseificiomolisanosanmarco.it\/#organization","name":"Caseificio Molisano San Marco","url":"https:\/\/caseificiomolisanosanmarco.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/caseificiomolisanosanmarco.it\/#\/schema\/logo\/image\/","url":"https:\/\/caseificiomolisanosanmarco.it\/wp-content\/uploads\/2021\/01\/LOGO-Transparent-e1610640037833.png","contentUrl":"https:\/\/caseificiomolisanosanmarco.it\/wp-content\/uploads\/2021\/01\/LOGO-Transparent-e1610640037833.png","width":150,"height":150,"caption":"Caseificio Molisano San Marco"},"image":{"@id":"https:\/\/caseificiomolisanosanmarco.it\/#\/schema\/logo\/image\/"}}]},"product_brand":"Dolci","product_price_amount":"30.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_condition":"new"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/caseificiomolisanosanmarco.it\/en\/wp-json\/wp\/v2\/product\/1855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/caseificiomolisanosanmarco.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/caseificiomolisanosanmarco.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/caseificiomolisanosanmarco.it\/en\/wp-json\/wp\/v2\/comments?post=1855"}],"version-history":[{"count":1,"href":"https:\/\/caseificiomolisanosanmarco.it\/en\/wp-json\/wp\/v2\/product\/1855\/revisions"}],"predecessor-version":[{"id":1858,"href":"https:\/\/caseificiomolisanosanmarco.it\/en\/wp-json\/wp\/v2\/product\/1855\/revisions\/1858"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/caseificiomolisanosanmarco.it\/en\/wp-json\/wp\/v2\/media\/1856"}],"wp:attachment":[{"href":"https:\/\/caseificiomolisanosanmarco.it\/en\/wp-json\/wp\/v2\/media?parent=1855"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/caseificiomolisanosanmarco.it\/en\/wp-json\/wp\/v2\/product_brand?post=1855"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/caseificiomolisanosanmarco.it\/en\/wp-json\/wp\/v2\/product_cat?post=1855"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/caseificiomolisanosanmarco.it\/en\/wp-json\/wp\/v2\/product_tag?post=1855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}